{"id":5,"date":"2007-06-17T03:01:59","date_gmt":"2007-06-17T03:01:59","guid":{"rendered":"http:\/\/blida.net\/fra\/?p=5"},"modified":"2007-07-14T14:02:20","modified_gmt":"2007-07-14T14:02:20","slug":"a-propos-du-site-de-linstitut-daeronautique","status":"publish","type":"post","link":"https:\/\/blida.net\/fra\/2007\/06\/17\/a-propos-du-site-de-linstitut-daeronautique\/","title":{"rendered":"A propos du Site de l&rsquo;institut d&rsquo;Aeronautique"},"content":{"rendered":"<p><font color=\"#ff0000\"><u>Mise \u00e0 jour le 14 juillet 2007<\/u><\/font>: \u00c9tant donn\u00e9 que c&rsquo;est la p\u00e9riode des inscriptions, on continue de recevoir beaucoup d&#8217;emails concernant l&rsquo;institut d&rsquo;a\u00e9ronautique. De ce fait, on vous demande de bien lire le post suivant avant de faire quoi que ce soit. Ce site blida.net n&rsquo;a rien \u00e0 voir avec l&rsquo;universite de blida et tous les emails sont <font color=\"#ff0000\"><u><strong>automatiquement d\u00e9truits<\/strong><\/u><\/font> non pas par m\u00e9chancet\u00e9 mais c&rsquo;est qu&rsquo;on n&rsquo;a aucune information actualis\u00e9e sur l&rsquo;institut d&rsquo;a\u00e9ronautique.\u00a0 Bonne chance pour vos inscriptions.<\/p>\n<p>&#8212;&#8212;&#8212;-<\/p>\n<p>On recoit beaucoup de requ\u00eates concernant le site web de l&rsquo;institut d&rsquo;aeronautique de l&rsquo;universit\u00e9 de Blida. En effet, j&rsquo;a mis en 2000 le site de l&rsquo;institut sur le domaine www.blida.net \u00e9tant donn\u00e9 que j&rsquo;enseignais au sein de cet institut. Par la m\u00eame occasion, mes cours \u00e9taient en ligne sur le meme domaine de 2000 \u00e0 2002 date \u00e0 laquelle j&rsquo;ai quitt\u00e9 l&rsquo;institut.<\/p>\n<p>Le site web a \u00e9t\u00e9 gard\u00e9 sur ce domaine jusqu&rsquo;a cette ann\u00e9e 2007 pour sa seule valeur d&rsquo;archive. Personne n&rsquo;a voulu le reprendre et depuis que j&rsquo;ai quitt\u00e9 l&rsquo;institut, je n&rsquo;ai plus de contact avec les administrateurs.<\/p>\n<p>De ce fait, il m&rsquo;est impossible de vous orienter car je n&rsquo;ai aucune info de contact, t\u00e9l\u00e9phone ou quoi que ce soit en relation avec cet institut.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Mise \u00e0 jour le 14 juillet 2007: \u00c9tant donn\u00e9 que c&rsquo;est la p\u00e9riode des inscriptions, on continue de recevoir beaucoup d&#8217;emails concernant l&rsquo;institut d&rsquo;a\u00e9ronautique. De ce fait, on vous demande de bien lire le post suivant avant de faire quoi que ce soit. Ce site blida.net n&rsquo;a rien \u00e0 voir avec l&rsquo;universite de blida et [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[3],"tags":[],"class_list":["post-5","post","type-post","status-publish","format-standard","hentry","category-news"],"jetpack_featured_media_url":"","_links":{"self":[{"href":"https:\/\/blida.net\/fra\/wp-json\/wp\/v2\/posts\/5","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/blida.net\/fra\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/blida.net\/fra\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/blida.net\/fra\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/blida.net\/fra\/wp-json\/wp\/v2\/comments?post=5"}],"version-history":[{"count":1,"href":"https:\/\/blida.net\/fra\/wp-json\/wp\/v2\/posts\/5\/revisions"}],"predecessor-version":[{"id":422,"href":"https:\/\/blida.net\/fra\/wp-json\/wp\/v2\/posts\/5\/revisions\/422"}],"wp:attachment":[{"href":"https:\/\/blida.net\/fra\/wp-json\/wp\/v2\/media?parent=5"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/blida.net\/fra\/wp-json\/wp\/v2\/categories?post=5"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/blida.net\/fra\/wp-json\/wp\/v2\/tags?post=5"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}